{"id":35681,"date":"2021-09-02T07:00:00","date_gmt":"2021-09-02T10:00:00","guid":{"rendered":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/?p=35681"},"modified":"2021-09-01T13:06:24","modified_gmt":"2021-09-01T16:06:24","slug":"reprograma-sustentabilidade-nos-meios-de-transporte","status":"publish","type":"post","link":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/diversos\/reprograma-sustentabilidade-nos-meios-de-transporte\/","title":{"rendered":"REprograma: sustentabilidade nos meios de transporte"},"content":{"rendered":"\n<p>A CVC est\u00e1 cada vez mais atenta aos impactos que podemos causar no ambiente. Pensando em dois pilares do <a href=\"https:\/\/www.cvc.com.br\/dicas-de-viagem\/institucional\/reprograma-cvc-compromisso-com-a-sustentabilidade-e-diversidade\/\" target=\"_blank\" rel=\"noreferrer noopener\">REprograma<\/a> (reduzir pegada e reeducar p\u00fablicos), apresentamos aqui parceiros que tamb\u00e9m est\u00e3o preocupados em neutralizar a emiss\u00e3o de carbono.<\/p>\n\n\n\n<h2><strong>Movida, locadora de carros<em> carbon free<\/em><\/strong><\/h2>\n\n\n\n<figure class=\"wp-container-2 wp-block-gallery-1 wp-block-gallery columns-1 is-cropped\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"546\" src=\"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/movida-locadora-de-carros-carbon-free-1024x546.png\" alt=\"\" data-id=\"35684\" data-full-url=\"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/movida-locadora-de-carros-carbon-free.png\" data-link=\"https:\/\/www.cvc.com.br\/dicas-de-viagem\/?attachment_id=35684\" class=\"wp-image-35684\" srcset=\"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/movida-locadora-de-carros-carbon-free-1024x546.png 1024w, https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/movida-locadora-de-carros-carbon-free-300x160.png 300w, https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/movida-locadora-de-carros-carbon-free-768x410.png 768w, https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/movida-locadora-de-carros-carbon-free-600x320.png 600w, https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/movida-locadora-de-carros-carbon-free.png 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p>A Movida come\u00e7ou a se preocupar com a emiss\u00e3o de carbono em 2013. Quando voc\u00ea aluga um dos carros da empresa, pode contratar a op\u00e7\u00e3o de<em> carbon free<\/em>, que funciona assim: \u00e9 feito o c\u00e1lculo de emiss\u00e3o de g\u00e1s carb\u00f4nico de sua loca\u00e7\u00e3o de acordo com quantos km voc\u00ea andou &#8211; a quantidade que foi emitida \u00e9 traduzida em quantidade de \u00e1rvores.<\/p>\n\n\n\n<p><br>Estas \u00e1rvores s\u00e3o plantadas no Brasil, no Corredor de Biodiversidade do Rio Araguaia, que fica localizado nos estados de Goi\u00e1s, Mato Grosso, Tocantins e Par\u00e1. Dessa forma, o reflorestamento das \u00e1reas degradadas proporcionam benef\u00edcios \u00e0 natureza e as comunidades locais, al\u00e9m de neutralizar as emiss\u00f5es de impacto negativo para a atmosfera.<\/p>\n\n\n\n<h2><strong>GOL, a companhia a\u00e9rea fez uma parceria com a Moss<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" width=\"1024\" height=\"546\" src=\"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/gol-parceria-com-a-moss-1024x546.png\" alt=\"\" class=\"wp-image-35687\" srcset=\"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/gol-parceria-com-a-moss-1024x546.png 1024w, https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/gol-parceria-com-a-moss-300x160.png 300w, https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/gol-parceria-com-a-moss-768x410.png 768w, https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/gol-parceria-com-a-moss-600x320.png 600w, https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-content\/uploads\/2021\/09\/gol-parceria-com-a-moss.png 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A GOL anunciou em 2021 uma nova medida para conten\u00e7\u00e3o da pegada de carbono. De forma pioneira no Brasil, todos os voos da companhia de ida e volta para Fernando de Noronha, a partir de Recife, ter\u00e3o emiss\u00e3o neutra de g\u00e1s carb\u00f4nico. Para que isso aconte\u00e7a, foi firmada uma parceria com a Moss, uma empresa que vende tokens de cr\u00e9dito de carbono, que \u00e9 quanto o carbono vale em blockchain. Funciona da seguinte forma: os cr\u00e9ditos v\u00eam de projetos florestais na Amaz\u00f4nia e o dinheiro investido serve para incentivar os projetos ambientais, ajudando os propriet\u00e1rios de terras e as comunidades locais a manterem as florestas em p\u00e9.Os passageiros que comprarem passagem para Fernando de Noronha conseguem resgatar com a Moss o certificado de cr\u00e9ditos de carbono j\u00e1 compensados depois de seus voos, al\u00e9m disso, se quiserem, podem comprar mais cr\u00e9ditos para neutralizar a emiss\u00e3o de g\u00e1s carb\u00f4nico para as outras rotas que comp\u00f5em a viagem depois de Recife (por exemplo, para voltar para S\u00e3o Paulo, Porto Alegre ou Belo Horizonte).\u00a0<\/p>\n\n\n\n<p>Essas a\u00e7\u00f5es tamb\u00e9m t\u00eam como intuito mostrar que \u00e9 necess\u00e1rio para as empresas se preocuparem com o impacto de seus servi\u00e7os no planeta e nas mudan\u00e7as clim\u00e1ticas, mas tamb\u00e9m lembrar a todos que a import\u00e2ncia de fazer a sua parte.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A CVC est\u00e1 cada vez mais atenta aos impactos que podemos causar no ambiente. Pensando em dois pilares do REprograma (reduzir pegada e reeducar p\u00fablicos), apresentamos aqui parceiros que tamb\u00e9m est\u00e3o preocupados em neutralizar a emiss\u00e3o de carbono. Movida, locadora de carros carbon free A Movida come\u00e7ou a se preocupar com a emiss\u00e3o de carbono [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":35683,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[1],"tags":[118,1799],"_links":{"self":[{"href":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-json\/wp\/v2\/posts\/35681"}],"collection":[{"href":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-json\/wp\/v2\/comments?post=35681"}],"version-history":[{"count":5,"href":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-json\/wp\/v2\/posts\/35681\/revisions"}],"predecessor-version":[{"id":35694,"href":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-json\/wp\/v2\/posts\/35681\/revisions\/35694"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-json\/wp\/v2\/media\/35683"}],"wp:attachment":[{"href":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-json\/wp\/v2\/media?parent=35681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-json\/wp\/v2\/categories?post=35681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cvc.com.br\/dicas-de-viagem\/wp-json\/wp\/v2\/tags?post=35681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}